{"id":7600,"date":"2023-08-16T10:56:28","date_gmt":"2023-08-16T15:56:28","guid":{"rendered":"https:\/\/expressometro.mx\/?p=7600"},"modified":"2023-08-16T10:56:29","modified_gmt":"2023-08-16T15:56:29","slug":"uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/","title":{"rendered":"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>* El rector de la UAEM\u00e9x devel\u00f3 la placa de la Primera Promoci\u00f3n del Diplomado en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico.\u00a0<\/p>\n\n\n\n<p>* En el acto fueron entregadas 10 pantallas, ocho proyectores y 100 pupitres para contribuir a que esta comunidad universitaria pueda desarrollar de mejor manera sus actividades acad\u00e9micas.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>A trav\u00e9s de la investigaci\u00f3n y la reflexi\u00f3n constantes, es posible mejorar nuestro entorno moral y contribuir a la construcci\u00f3n de una administraci\u00f3n p\u00fablica m\u00e1s justa, honesta y transparente, destac\u00f3 el rector de la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM\u00e9x), al develar la placa de la Primera Promoci\u00f3n del Diplomado en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico, en la Facultad de Ciencias Pol\u00edticas y Sociales.<\/p>\n\n\n\n<p>Acompa\u00f1ado de la secretar\u00eda de Administraci\u00f3n, Er\u00e9ndira Fierro Moreno; la&nbsp; directora de la Facultad, Laura Elizabeth Benhumea Gonz\u00e1lez; el titular del \u00d3rgano Interno de Control, Victorino Barrios D\u00e1valos, y la coordinadora del Diplomado Superior en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico, Nuria Ferreira Ma\u00f1a, Barrera D\u00edaz apunt\u00f3 que las y los egresados ha demostrado un compromiso ejemplar, al participar activamente en las discusiones, debates y proyectos que formaron parte de este programa de educaci\u00f3n continua.<\/p>\n\n\n\n<p>\u201cComo primera generaci\u00f3n de este diplomado son agentes de cambio. Por ello, les insto a que apliquen responsablemente lo que han aprendido y se conviertan en modelos a seguir para otros funcionarios y acad\u00e9micos que est\u00e1n comprometidos en la lucha contra la corrupci\u00f3n y la promoci\u00f3n de una cultura \u00e9tica en el servicio p\u00fablico\u201d, abund\u00f3.<\/p>\n\n\n\n<p>Por su parte, la coordinadora del Diplomado Superior en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico, Nuria Ferreira Ma\u00f1a, apunt\u00f3 que las y los egresados de este programa son capaces de emplear instrumentos \u00e9ticos de aplicaci\u00f3n pr\u00e1ctica, elaborar c\u00f3digos, programas y modelos, as\u00ed como estructurar pol\u00edticas en \u00e9tica. Todo ello, con el prop\u00f3sito de enfrentarse a la corrupci\u00f3n dentro de diversos espacios.<\/p>\n\n\n\n<p>\u201cLa Administraci\u00f3n 2021-2025, encabezada por el rector Carlos Eduardo Barrera D\u00edaz, se ha sumado al compromiso de marcar una diferencia a trav\u00e9s de proyectos y acciones \u00e9ticas que no tienen otra meta sino el bien de la UAEM\u00e9x\u201d, destac\u00f3.&nbsp;&nbsp;&nbsp;&nbsp;<\/p>\n\n\n\n<p>Previo a la develaci\u00f3n de la placa, se llev\u00f3 a cabo la mesa de an\u00e1lisis \u201cEl rol de la universidad en el fomento de la \u00e9tica p\u00fablica\u201d, que cont\u00f3 la participaci\u00f3n del titular del \u00d3rgano Interno de Control, Victorino Barrios D\u00e1valos; \u00d3scar Diego Bautista, profesor investigador de la UAEM\u00e9x, y Jaime Rodr\u00edguez Alba, especialista en \u00e9tica.<\/p>\n\n\n\n<p>En el acto fueron entregadas 10 pantallas, ocho proyectores y 100 pupitres para contribuir a que esta comunidad universitaria pueda desarrollar de mejor manera sus actividades acad\u00e9micas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El rector de la UAEM\u00e9x devel\u00f3 la placa de la Primera Promoci\u00f3n del Diplomado en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":7602,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,3,6],"tags":[313,1982,82],"class_list":["post-7600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-gobierno","category-seguridad","tag-carlos-eduardo-barrera-diaz","tag-edomex","tag-uaemex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"El rector de la UAEM\u00e9x devel\u00f3 la placa de la Primera Promoci\u00f3n del Diplomado en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-16T15:56:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T15:56:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/expressometro.mx\/wp-content\/uploads\/2023\/08\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1440\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expresso Metropolitano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expresso Metropolitano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/\"},\"author\":{\"name\":\"Expresso Metropolitano\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\"},\"headline\":\"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO\",\"datePublished\":\"2023-08-16T15:56:28+00:00\",\"dateModified\":\"2023-08-16T15:56:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg\",\"keywords\":[\"Carlos Eduardo Barrera D\u00edaz\",\"Edomex\",\"UAEMex\"],\"articleSection\":[\"Educaci\u00f3n\",\"Gobierno\",\"Seguridad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/\",\"name\":\"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg\",\"datePublished\":\"2023-08-16T15:56:28+00:00\",\"dateModified\":\"2023-08-16T15:56:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg\",\"width\":1440,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2023\\\/08\\\/16\\\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\",\"name\":\"Expresso Metropolitano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"caption\":\"Expresso Metropolitano\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/diego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/","og_locale":"es_MX","og_type":"article","og_title":"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO - Expresso Metropolitano","og_description":"El rector de la UAEM\u00e9x devel\u00f3 la placa de la Primera Promoci\u00f3n del Diplomado en \u00c9tica P\u00fablica y Prevenci\u00f3n de la Corrupci\u00f3n en el Servicio P\u00fablico.\u00a0","og_url":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/","og_site_name":"Expresso Metropolitano","article_published_time":"2023-08-16T15:56:28+00:00","article_modified_time":"2023-08-16T15:56:29+00:00","og_image":[{"width":1440,"height":960,"url":"http:\/\/expressometro.mx\/wp-content\/uploads\/2023\/08\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg","type":"image\/jpeg"}],"author":"Expresso Metropolitano","twitter_misc":{"Escrito por":"Expresso Metropolitano","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/"},"author":{"name":"Expresso Metropolitano","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d"},"headline":"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO","datePublished":"2023-08-16T15:56:28+00:00","dateModified":"2023-08-16T15:56:29+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2023\/08\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg","keywords":["Carlos Eduardo Barrera D\u00edaz","Edomex","UAEMex"],"articleSection":["Educaci\u00f3n","Gobierno","Seguridad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/","url":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/","name":"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2023\/08\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg","datePublished":"2023-08-16T15:56:28+00:00","dateModified":"2023-08-16T15:56:29+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2023\/08\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2023\/08\/UAEM-Prevencion-de-la-Corrupcion-160823-1.jpg","width":1440,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2023\/08\/16\/uaemex-comprometida-con-la-prevencion-de-la-corrupcion-en-el-servicio-publico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"UAEM\u00c9X, COMPROMETIDA CON LA PREVENCI\u00d3N DE LA CORRUPCI\u00d3N EN EL SERVICIO P\u00daBLICO"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d","name":"Expresso Metropolitano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","caption":"Expresso Metropolitano"},"url":"https:\/\/expressometro.mx\/index.php\/author\/diego\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/7600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=7600"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/7600\/revisions"}],"predecessor-version":[{"id":7603,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/7600\/revisions\/7603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/7602"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=7600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=7600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=7600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}