{"id":5053,"date":"2022-01-28T22:00:49","date_gmt":"2022-01-29T04:00:49","guid":{"rendered":"https:\/\/expressometro.mx\/?p=5053"},"modified":"2022-01-28T22:00:50","modified_gmt":"2022-01-29T04:00:50","slug":"demandan-municipios-un-arranque-fuerte-para-el-desarrollo","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/","title":{"rendered":"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO"},"content":{"rendered":"\n<ul class=\"wp-block-list\" style=\"font-size:18px\"><li>El diputado federal Gustavo C\u00e1rdenas Monroy llam\u00f3 a integrar en las Mesas de Fortalecimiento a los funcionarios federales que tienen a cargo diferentes programas del gobierno.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Las administraciones municipales que van iniciando su gesti\u00f3n tienen que arrancar fuerte para el desarrollo de la gente, con fortalecimiento en las haciendas p\u00fablicas y la cooperaci\u00f3n entre los diferentes niveles de gobierno, dej\u00f3 en claro el diputado federal Gustavo C\u00e1rdenas Monroy.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante la Mesa de Fortalecimiento Municipal Regi\u00f3n III realizada en Temascalcingo, manifest\u00f3 que se debe sumar a los funcionar\u00edas federales para buscar acuerdos que permitan la posibilidad de desarrollo, no para reclamarles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En la Trig\u00e9sima Sesi\u00f3n Ordinaria encabezada por la Secretar\u00eda del Campo, Mercedes Col\u00edn Guadarrama, sostuvo que los acercamientos que en esa mesa se generan entre las dependencias estatales y los gobiernos municipales, favorecen la cooperaci\u00f3n, la coordinaci\u00f3n y la suma de esfuerzos entre esos dos niveles de gobierno, incrementando la calidad en la atenci\u00f3n y los buenos resultados en favor de la ciudadan\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gustavo C\u00e1rdenas Monroy al hacer uso de la voz reconoci\u00f3 el trabajo itinerante de la secretaria del campo, qui\u00e9n incansablemente recorre todas las regiones de la geograf\u00eda mexiquense y con una especial cercan\u00eda la regi\u00f3n norte de la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se refiri\u00f3 a Col\u00edn Guadarrama como una servidora p\u00fablica confiable y reconoci\u00f3 su poder de convocatoria para reunir a todos los Presidentes Municipales y Legisladores tanto Locales como Federales, a quienes el Diputado Federal por Atlacomulco ubic\u00f3 como corresponsables directos de que las cosas salgan mejor que en el pasado reciente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Exhort\u00f3 a la responsable de la mesa, para que en ejercicios subsecuentes sean invitadas m\u00e1s dependencias incluso federales, acerc\u00e1ndolas a los ayuntamientos, pues estos van iniciando y no pueden arrancar lento; necesitan de la gesti\u00f3n ante las dependencias para cumplir las expectativas de los ciudadanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resalt\u00f3 que quienes vivimos en el norte del estado, siempre nos hemos visto como hermanos, como compa\u00f1eros que cuando podemos ayudar a alguien, no lo hacemos trat\u00e1ndolo de detener, sino pensando \u00bfC\u00f3mo lo podemos promover?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha reuni\u00f3n se llev\u00f3 a cabo en el municipio de Temascalcingo, contando con la presencia de los presidentes que integran esa regi\u00f3n; tambi\u00e9n asistieron los Diputados Federales: Ricardo Aguilar Castillo, Eduardo Zarzosa S\u00e1nchez y Miguel S\u00e1mano Peralta; adem\u00e1s de Iv\u00e1n Esquer Cruz Diputado Local por el Distrito XIII con cabecera en Atlacomulco y los responsables regionales de las dependencias del gobierno estatal.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-720x480.jpeg\" alt=\"\" data-id=\"5055\" data-link=\"https:\/\/expressometro.mx\/?attachment_id=5055\" class=\"wp-image-5055\" srcset=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-720x480.jpeg 720w, https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-548x365.jpeg 548w, https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-768x512.jpeg 768w, https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM.jpeg 960w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-1-720x480.jpeg\" alt=\"\" data-id=\"5056\" data-full-url=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-1.jpeg\" data-link=\"https:\/\/expressometro.mx\/?attachment_id=5056\" class=\"wp-image-5056\" srcset=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-1-720x480.jpeg 720w, https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-1-548x365.jpeg 548w, https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-1-768x512.jpeg 768w, https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.23-PM-1.jpeg 960w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><\/li><\/ul><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>El diputado federal Gustavo C\u00e1rdenas Monroy llam\u00f3 a integrar en las Mesas de Fortalecimiento a los funcionarios federales que tienen a cargo diferentes programas del gobierno.<\/p>\n","protected":false},"author":2,"featured_media":5057,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[891],"class_list":["post-5053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","tag-gustavo-cardenas-2"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"El diputado federal Gustavo C\u00e1rdenas Monroy llam\u00f3 a integrar en las Mesas de Fortalecimiento a los funcionarios federales que tienen a cargo diferentes programas del gobierno.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T04:00:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-29T04:00:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cecilia Vega\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cecilia Vega\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/\"},\"author\":{\"name\":\"Cecilia Vega\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/67a95b8e3862085c7598f66237488f1f\"},\"headline\":\"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO\",\"datePublished\":\"2022-01-29T04:00:49+00:00\",\"dateModified\":\"2022-01-29T04:00:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/\"},\"wordCount\":438,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg\",\"keywords\":[\"Gustavo C\u00e1rdenas\"],\"articleSection\":[\"Gobierno\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/\",\"name\":\"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg\",\"datePublished\":\"2022-01-29T04:00:49+00:00\",\"dateModified\":\"2022-01-29T04:00:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2022\\\/01\\\/28\\\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/67a95b8e3862085c7598f66237488f1f\",\"name\":\"Cecilia Vega\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g\",\"caption\":\"Cecilia Vega\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/cecilia-vega\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/","og_locale":"es_MX","og_type":"article","og_title":"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO - Expresso Metropolitano","og_description":"El diputado federal Gustavo C\u00e1rdenas Monroy llam\u00f3 a integrar en las Mesas de Fortalecimiento a los funcionarios federales que tienen a cargo diferentes programas del gobierno.","og_url":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/","og_site_name":"Expresso Metropolitano","article_published_time":"2022-01-29T04:00:49+00:00","article_modified_time":"2022-01-29T04:00:50+00:00","og_image":[{"width":960,"height":640,"url":"http:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg","type":"image\/jpeg"}],"author":"Cecilia Vega","twitter_misc":{"Escrito por":"Cecilia Vega","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/"},"author":{"name":"Cecilia Vega","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/67a95b8e3862085c7598f66237488f1f"},"headline":"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO","datePublished":"2022-01-29T04:00:49+00:00","dateModified":"2022-01-29T04:00:50+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/"},"wordCount":438,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg","keywords":["Gustavo C\u00e1rdenas"],"articleSection":["Gobierno"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/","url":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/","name":"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg","datePublished":"2022-01-29T04:00:49+00:00","dateModified":"2022-01-29T04:00:50+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2022\/01\/WhatsApp-Image-2022-01-28-at-6.49.22-PM.jpeg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2022\/01\/28\/demandan-municipios-un-arranque-fuerte-para-el-desarrollo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"DEMANDAN MUNICIPIOS UN ARRANQUE FUERTE PARA EL DESARROLLO"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/67a95b8e3862085c7598f66237488f1f","name":"Cecilia Vega","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g","caption":"Cecilia Vega"},"url":"https:\/\/expressometro.mx\/index.php\/author\/cecilia-vega\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/5053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=5053"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/5053\/revisions"}],"predecessor-version":[{"id":5058,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/5053\/revisions\/5058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/5057"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=5053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=5053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=5053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}