{"id":3791,"date":"2021-10-17T17:14:56","date_gmt":"2021-10-17T22:14:56","guid":{"rendered":"http:\/\/expressometro.mx\/?p=3791"},"modified":"2021-10-17T17:14:57","modified_gmt":"2021-10-17T22:14:57","slug":"no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/","title":{"rendered":"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez"},"content":{"rendered":"\n<p>El presidente municipal electo de Coacalco, David S\u00e1nchez Isidoro, asegur\u00f3 que detendr\u00e1n el enjuague que lleva a cabo Morena para revertir en los tribunales la voluntad del pueblo que eligi\u00f3 un cambio de gobierno y vot\u00f3 por la coalici\u00f3n Va por el Estado de M\u00e9xico.<br>\u00a0<br>Dijo que si bien el Tribunal Electoral del Estado de M\u00e9xico ratific\u00f3 su triunfo el pasado 7 de octubre, tambi\u00e9n invalid\u00f3 la votaci\u00f3n en 18 casillas, d\u00e1ndole la raz\u00f3n a Morena, pese a que present\u00f3 informaci\u00f3n falsa a trav\u00e9s de su director jur\u00eddico y del secretario del ayuntamiento.<br>\u00a0<br>Los morenistas se\u00f1alan que autoridades auxiliares en turno hab\u00edan estado en las mesas directivas de casilla, cosa que es mentira y falsean otros nombres diferentes a los verdaderos delegados, expuso el abanderado del PRI, PAN y PRD.<br>\u00a0<br>De esta forma, dijo, el tribunal mexiquense anula dichas casillas\u00a0bajo el argumento de que en ellas actuaron como funcionarios personas no acreditadas por el \u00f3rgano electoral local, con lo que quitan poco m\u00e1s del 50 por ciento de la diferencia de la votaci\u00f3n.<br>\u00a0<br>S\u00e1nchez Isidoro dijo que lo preocupante es que, aunque el tribunal local les dio el triunfo, dejan pendientes 13 casillas para que la Sala Regional pueda jalarlos, y con el argumento de que participaron autoridades auxiliares, anulen tambi\u00e9n esas casillas y les quiten el triunfo obtenido en las urnas.<br>\u00a0<br>Por ello, dijo, est\u00e1n buscando que los magistrados de la Sala Regional del Tribunal Electoral del Poder Judicial de la Federaci\u00f3n (TEPJF), con un criterio responsable, y basado en pruebas reales y s\u00f3lidas, le la raz\u00f3n a la coalici\u00f3n Va por el Estado de M\u00e9xico.<br>\u00a0<br>\u201cApelamos a que la Sala Regional, con las pruebas que estamos interponiendo, rectifique la resoluci\u00f3n del Tribunal mexiquense y nos devuelvan las 18 casillas que nos anularon indebidamente y proteger las otras 13 donde argumentan la participaci\u00f3n de autoridades auxiliares, lo cual es falso, de acuerdo con el listado del ayuntamiento\u201d.<br>\u00a0<br>David S\u00e1nchez sostuvo que, lamentablemente, el Tribunal mexiquense se prest\u00f3 al juego de Morena para que pudieran confabular con esas acciones. Primero, d\u00e1ndoles una ampliaci\u00f3n de demanda que es anticonstitucional, y segunda, recibiendo nuevas casillas con supuestos delegados falsos emitidos por el ayuntamiento.<br>\u00a0<br>Se\u00f1al\u00f3 que est\u00e1n a la espera de que en 15 d\u00edas resuelva la Sala Regional y rectifique la determinaci\u00f3n de los magistrados mexiquenses, quienes tomaron una decisi\u00f3n con la \u00fanica informaci\u00f3n que les dio el ayuntamiento, que en este caso es juez y parte, sin dar vista a las partes involucradas en el juicio electoral, con lo cual los dejaron en estado de indefensi\u00f3n.<br>\u00a0<br>Dej\u00f3 en claro que no dejar\u00e1n pasar las artima\u00f1as de Morena, pues el pueblo de Coacalco ya decidi\u00f3 su voto en favor de la Alianza y no es justo que por d\u00e1divas millonarias del alcalde y abanderado de Morena, Darwin Eslava Gami\u00f1o, se compren voluntades para invalidar el triunfo del PRI, PAN y PRD.<br>\u00a0<br>El alcalde electo subray\u00f3 que se trata de\u00a0 una artima\u00f1a para confundir la justicia, traicionando la democracia del municipio. Morena falsea informaci\u00f3n, e incluso el tribunal les dio una ampliaci\u00f3n de demanda que es anticonstitucional, para que pudieran justificar la anulaci\u00f3n de 18 casillas, reiter\u00f3.<br>\u00a0<br>\u201cMorena no ha entendido su derrota y no solo nos fuimos al recuento de votos, el tribunal mexiquense incurri\u00f3 en irresponsabilidad porque le dieron ampliaci\u00f3n de demanda, Morena falsea informaci\u00f3n y no permitiremos que se pase por encima de la voluntad del pueblo de Coacalco, enfatiz\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"http:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-1.jpeg\" alt=\"\" class=\"wp-image-3794\" srcset=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-1.jpeg 400w, https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-1-365x365.jpeg 365w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Exigir\u00e1n que la Sala Regional del TEPJF, con un criterio responsable y basado en pruebas reales y s\u00f3lidas, le la raz\u00f3n a la coalici\u00f3n Va por el Estado de M\u00e9xico.<\/p>\n","protected":false},"author":2,"featured_media":3795,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[231],"tags":[905,904],"class_list":["post-3791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-coacalco","tag-david-sanchez"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"Exigir\u00e1n que la Sala Regional del TEPJF, con un criterio responsable y basado en pruebas reales y s\u00f3lidas, le la raz\u00f3n a la coalici\u00f3n Va por el Estado de M\u00e9xico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-17T22:14:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-17T22:14:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1066\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cecilia Vega\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cecilia Vega\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/\"},\"author\":{\"name\":\"Cecilia Vega\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/67a95b8e3862085c7598f66237488f1f\"},\"headline\":\"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez\",\"datePublished\":\"2021-10-17T22:14:56+00:00\",\"dateModified\":\"2021-10-17T22:14:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/\"},\"wordCount\":620,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg\",\"keywords\":[\"Coacalco\",\"David S\u00e1nchez\"],\"articleSection\":[\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/\",\"name\":\"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg\",\"datePublished\":\"2021-10-17T22:14:56+00:00\",\"dateModified\":\"2021-10-17T22:14:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg\",\"width\":1600,\"height\":1066},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2021\\\/10\\\/17\\\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/67a95b8e3862085c7598f66237488f1f\",\"name\":\"Cecilia Vega\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g\",\"caption\":\"Cecilia Vega\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/cecilia-vega\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/","og_locale":"es_MX","og_type":"article","og_title":"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez - Expresso Metropolitano","og_description":"Exigir\u00e1n que la Sala Regional del TEPJF, con un criterio responsable y basado en pruebas reales y s\u00f3lidas, le la raz\u00f3n a la coalici\u00f3n Va por el Estado de M\u00e9xico.","og_url":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/","og_site_name":"Expresso Metropolitano","article_published_time":"2021-10-17T22:14:56+00:00","article_modified_time":"2021-10-17T22:14:57+00:00","og_image":[{"width":1600,"height":1066,"url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg","type":"image\/jpeg"}],"author":"Cecilia Vega","twitter_misc":{"Escrito por":"Cecilia Vega","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/"},"author":{"name":"Cecilia Vega","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/67a95b8e3862085c7598f66237488f1f"},"headline":"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez","datePublished":"2021-10-17T22:14:56+00:00","dateModified":"2021-10-17T22:14:57+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/"},"wordCount":620,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg","keywords":["Coacalco","David S\u00e1nchez"],"articleSection":["Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/","url":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/","name":"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg","datePublished":"2021-10-17T22:14:56+00:00","dateModified":"2021-10-17T22:14:57+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2021\/10\/WhatsApp-Image-2021-10-17-at-15.27.09-2.jpeg","width":1600,"height":1066},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2021\/10\/17\/no-vamos-a-permitir-fraude-electoral-en-coacalco-david-sanchez\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"No vamos a permitir fraude electoral en Coacalco: David S\u00e1nchez"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/67a95b8e3862085c7598f66237488f1f","name":"Cecilia Vega","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/13aae9944ab2ee472a9e407c9487fdbd03b049abaa559af32fe5dbcf615c981b?s=96&d=mm&r=g","caption":"Cecilia Vega"},"url":"https:\/\/expressometro.mx\/index.php\/author\/cecilia-vega\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/3791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=3791"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/3791\/revisions"}],"predecessor-version":[{"id":3796,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/3791\/revisions\/3796"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/3795"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=3791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=3791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=3791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}