{"id":1404,"date":"2020-03-26T15:13:41","date_gmt":"2020-03-26T21:13:41","guid":{"rendered":"http:\/\/expressometro.mx\/?p=1404"},"modified":"2020-03-26T15:13:42","modified_gmt":"2020-03-26T21:13:42","slug":"son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/","title":{"rendered":"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Instituto de Salud del Estado de M\u00e9xico (ISEM) informa que a trav\u00e9s de las 60 Unidades M\u00f3viles dispuestas en Hospitales de Alta Especialidad, Generales y Municipales, a la fecha se han realizado mil 091 atenciones y se aplicaron 750 protocolos para probables casos de COVID-19, detectando 66 posibles por esta v\u00eda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dicha estrategia tiene como objetivo ser un primer filtro para personas que refieren s\u00edntomas respiratorios o alg\u00fan factor de sospecha a esta enfermedad, a fin de mantener la integridad sanitaria de los nosocomios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las acciones realizadas en estas Unidades M\u00f3viles permiten atender integralmente a las personas sin tener que ingresar a los hospitales, de tal forma que en caso de ser positivos al protocolo de caso sospechoso, se referir\u00e1 al \u00e1rea de Epidemiolog\u00eda de la Unidad Hospitalaria para su valoraci\u00f3n cl\u00ednica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Secretar\u00eda de Salud del Estado de M\u00e9xico a cargo de Gabriel O\u2019Shea Cuevas, detalla que estas acciones corren a cargo de la Coordinaci\u00f3n de Fortalecimiento a la Atenci\u00f3n M\u00e9dica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, se\u00f1ala que el organismo cuenta con una plataforma digital para el reporte de atenciones y casos sospechosos en l\u00ednea, el cual permite, en tiempo real, contar con la informaci\u00f3n de todas las unidades m\u00f3viles instaladas en los hospitales del estado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Es importante se\u00f1alar que de detectarse un caso positivo a COVID-19, es el nosocomio quien se encarga de tomar la muestra y dar seguimiento al paciente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La dependencia exhorta a la ciudadan\u00eda a seguir las recomendaciones de la Jornada Nacional de Sana Distancia y permanecer en sus hogares, adem\u00e1s de tener especial cuidado de los adultos mayores, sobre todo si padecen diabetes, hipertensi\u00f3n o problemas cardiacos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Instituto de Salud del Estado de M\u00e9xico (ISEM) informa que a trav\u00e9s de las 60 Unidades M\u00f3viles dispuestas en Hospitales de Alta Especialidad, Generales y Municipales, a la fecha se han realizado mil 091 atenciones y se aplicaron 750 protocolos para probables casos de COVID-19, detectando 66 posibles por esta v\u00eda. Dicha estrategia tiene como objetivo ser un primer filtro para personas que refieren s\u00edntomas respiratorios o alg\u00fan factor de sospecha a esta enfermedad, a fin de mantener la integridad sanitaria de los nosocomios. Las acciones realizadas en estas&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-otros"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19 - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19 - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"El Instituto de Salud del Estado de M\u00e9xico (ISEM) informa que a trav\u00e9s de las 60 Unidades M\u00f3viles dispuestas en Hospitales de Alta Especialidad, Generales y Municipales, a la fecha se han realizado mil 091 atenciones y se aplicaron 750 protocolos para probables casos de COVID-19, detectando 66 posibles por esta v\u00eda. Dicha estrategia tiene como objetivo ser un primer filtro para personas que refieren s\u00edntomas respiratorios o alg\u00fan factor de sospecha a esta enfermedad, a fin de mantener la integridad sanitaria de los nosocomios. Las acciones realizadas en estas&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-26T21:13:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-26T21:13:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2020\/03\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"853\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expresso Metropolitano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expresso Metropolitano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/\"},\"author\":{\"name\":\"Expresso Metropolitano\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\"},\"headline\":\"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19\",\"datePublished\":\"2020-03-26T21:13:41+00:00\",\"dateModified\":\"2020-03-26T21:13:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg\",\"articleSection\":[\"Otros\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/\",\"name\":\"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19 - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg\",\"datePublished\":\"2020-03-26T21:13:41+00:00\",\"dateModified\":\"2020-03-26T21:13:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg\",\"width\":1280,\"height\":853},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2020\\\/03\\\/26\\\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\",\"name\":\"Expresso Metropolitano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"caption\":\"Expresso Metropolitano\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/diego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19 - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/","og_locale":"es_MX","og_type":"article","og_title":"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19 - Expresso Metropolitano","og_description":"El Instituto de Salud del Estado de M\u00e9xico (ISEM) informa que a trav\u00e9s de las 60 Unidades M\u00f3viles dispuestas en Hospitales de Alta Especialidad, Generales y Municipales, a la fecha se han realizado mil 091 atenciones y se aplicaron 750 protocolos para probables casos de COVID-19, detectando 66 posibles por esta v\u00eda. Dicha estrategia tiene como objetivo ser un primer filtro para personas que refieren s\u00edntomas respiratorios o alg\u00fan factor de sospecha a esta enfermedad, a fin de mantener la integridad sanitaria de los nosocomios. Las acciones realizadas en estas&hellip;","og_url":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/","og_site_name":"Expresso Metropolitano","article_published_time":"2020-03-26T21:13:41+00:00","article_modified_time":"2020-03-26T21:13:42+00:00","og_image":[{"width":1280,"height":853,"url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2020\/03\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg","type":"image\/jpeg"}],"author":"Expresso Metropolitano","twitter_misc":{"Escrito por":"Expresso Metropolitano","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/"},"author":{"name":"Expresso Metropolitano","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d"},"headline":"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19","datePublished":"2020-03-26T21:13:41+00:00","dateModified":"2020-03-26T21:13:42+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2020\/03\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg","articleSection":["Otros"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/","url":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/","name":"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19 - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2020\/03\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg","datePublished":"2020-03-26T21:13:41+00:00","dateModified":"2020-03-26T21:13:42+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2020\/03\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2020\/03\/723B284F-5ADB-4F11-8779-D52F77197EDF.jpeg","width":1280,"height":853},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2020\/03\/26\/son-unidades-moviles-primer-filtro-en-hospitales-para-pacientes-con-sospecha-de-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"SON UNIDADES M\u00d3VILES PRIMER FILTRO EN HOSPITALES PARA PACIENTES CON SOSPECHA DE COVID-19"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d","name":"Expresso Metropolitano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","caption":"Expresso Metropolitano"},"url":"https:\/\/expressometro.mx\/index.php\/author\/diego\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/1404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1404"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/1404\/revisions"}],"predecessor-version":[{"id":1406,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/1404\/revisions\/1406"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/1405"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}