{"id":11948,"date":"2026-05-27T15:31:59","date_gmt":"2026-05-27T21:31:59","guid":{"rendered":"https:\/\/expressometro.mx\/?p=11948"},"modified":"2026-05-29T15:42:25","modified_gmt":"2026-05-29T21:42:25","slug":"convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/","title":{"rendered":"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Diputaci\u00f3n Permanente, presidida por la diputada Martha Azucena Camacho Reynoso (morena), convoc\u00f3 a las, le y los diputados a la realizaci\u00f3n del Sexto Periodo Extraordinario de Sesiones de la LXII Legislatura mexiquense este 29 de mayo a las 10:00 horas para deliberar reformas referentes al Poder Judicial, nulidad de elecciones por intervenci\u00f3n extranjera y disposiciones del C\u00f3digo Electoral del Estado de M\u00e9xico.<br>De acuerdo con el documento, le\u00eddo por el diputado Eduardo Zarzosa S\u00e1nchez (PRI), en el primer punto del d\u00eda se someter\u00e1 a discusi\u00f3n y votaci\u00f3n la minuta con proyecto de decreto por el que se reforman y adicionan diversas disposiciones de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, en materia de reforma del Poder Judicial, remitida por la C\u00e1mara de Senadores del Congreso de la Uni\u00f3n.<br>Con esta iniciativa, de acuerdo con el Senado de la Rep\u00fablica, se busca \u201cfortalecer los mecanismos que permiten que la voluntad del pueblo se exprese con eficacia\u201d, para lo cual se propone que la fecha de la elecci\u00f3n del Poder Judicial se modifique para que se celebre el 1 de junio de 2028 y no en 2027 (como originalmente se plante\u00f3).<br>En un segundo punto del d\u00eda, se deliberar\u00e1 la minuta con Proyecto de Decreto por el que se adiciona un inciso a la base VI del art\u00edculo 41 de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos, para introducir una nueva causal de nulidad de elecciones por intervenci\u00f3n extranjera, remitida por la C\u00e1mara de Senadores del Congreso de la Uni\u00f3n.<br>Finalmente, una iniciativa de decreto que reforma y adiciona diversas disposiciones del C\u00f3digo Electoral del Estado de M\u00e9xico.<br>Cabe se\u00f1alar que los tres asuntos del orden del d\u00eda est\u00e1n marcados como de urgente y obvia resoluci\u00f3n.<br>En la lectura del documento se destac\u00f3 que, el desarrollo del per\u00edodo extraordinario, atiende tambi\u00e9n, lo acordado por la Junta de Coordinaci\u00f3n Pol\u00edtica de la LXII Legislatura mexiquense, presidida por el diputado Jos\u00e9 Francisco V\u00e1zquez Rodr\u00edguez (morena), que ha determinado la preparaci\u00f3n, oportuna, de los actos necesarios, incluyendo el desarrollo del per\u00edodo extraordinario, para que, el Congreso est\u00e9 en aptitud de emitir su voto, como integrante del \u00d3rgano Revisor de la Constituci\u00f3n Pol\u00edtica de los Estados Unidos Mexicanos ante las minutas de reforma constitucional que ser\u00e1n turnadas y de las adecuaciones de la legislaci\u00f3n general en la materia que realice el Congreso de la Uni\u00f3n.<br>A\u00f1ade que, la agenda del per\u00edodo extraordinario que realizan las c\u00e1maras de diputados y senadores del Congreso de la Uni\u00f3n buscan resolver las iniciativas que reforman y adicionan la Constituci\u00f3n Pol\u00edtica federal, formuladas por Claudia Sheinbaum Pardo, presidenta de la Rep\u00fablica, y por el diputado federal Ricardo Monreal \u00c1vila.<br>\u201cLas minutas con las que, seguramente, concluir\u00e1n los trabajos y las modificaciones a la legislaci\u00f3n general en la materia, requerir\u00e1n, del conocimiento y, en su caso, del voto correspondiente de los congresos de las entidades federativas, as\u00ed como la armonizaci\u00f3n del marco jur\u00eddico estatal\u201d, puntualiza el documento.<br>Recibe Diputaci\u00f3n Permanente comunicado sobre salida al extranjero<br>Por otro lado, la presidencia de la Diputaci\u00f3n Permanente recibi\u00f3 el comunicado de Fernando Flores Fern\u00e1ndez, alcalde de Metepec, sobre su salida de trabajo el 23 y 24 de abril a Miami, Florida, en Estados Unidos de Am\u00e9rica. El documento fue le\u00eddo por la diputada Mar\u00eda del Consuelo Estrada Plata (PT).<br>Al respecto, el legislador Octavio Mart\u00ednez Vargas (morena) se\u00f1al\u00f3 que se trata de un asunto de car\u00e1cter tur\u00edstico, por lo que existe una Secretar\u00eda de Turismo federal y un \u00e1rea de turismo en la entidad. Cuestion\u00f3 que no se haya informado una utilidad social para las y los habitantes de Metepec y, en ese sentido, consider\u00f3 que las y los alcaldes deben replantear sus prioridades cuando reciban este tipo de invitaciones al extranjero, ya que no debe permitirse el uso de recursos p\u00fablicos para viajes de car\u00e1cter recreativo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Diputaci\u00f3n Permanente, presidida por la diputada Martha Azucena Camacho Reynoso (morena), convoc\u00f3 a las, le y los diputados a la realizaci\u00f3n del Sexto Periodo Extraordinario de Sesiones de la LXII Legislatura mexiquense este 29 de mayo a las 10:00 horas para deliberar reformas referentes al Poder Judicial, nulidad de elecciones por intervenci\u00f3n extranjera y disposiciones del C\u00f3digo Electoral del Estado de M\u00e9xico.<\/p>\n","protected":false},"author":1,"featured_media":11950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1,231],"tags":[1982,86],"class_list":["post-11948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno","category-otros","category-politica","tag-edomex","tag-gem"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"La Diputaci\u00f3n Permanente, presidida por la diputada Martha Azucena Camacho Reynoso (morena), convoc\u00f3 a las, le y los diputados a la realizaci\u00f3n del Sexto Periodo Extraordinario de Sesiones de la LXII Legislatura mexiquense este 29 de mayo a las 10:00 horas para deliberar reformas referentes al Poder Judicial, nulidad de elecciones por intervenci\u00f3n extranjera y disposiciones del C\u00f3digo Electoral del Estado de M\u00e9xico.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-27T21:31:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-29T21:42:25+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/expressometro.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1067\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expresso Metropolitano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expresso Metropolitano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/\"},\"author\":{\"name\":\"Expresso Metropolitano\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\"},\"headline\":\"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES\",\"datePublished\":\"2026-05-27T21:31:59+00:00\",\"dateModified\":\"2026-05-29T21:42:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/\"},\"wordCount\":703,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg\",\"keywords\":[\"Edomex\",\"GEM\"],\"articleSection\":[\"Gobierno\",\"Otros\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/\",\"name\":\"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg\",\"datePublished\":\"2026-05-27T21:31:59+00:00\",\"dateModified\":\"2026-05-29T21:42:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg\",\"width\":1600,\"height\":1067},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2026\\\/05\\\/27\\\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\",\"name\":\"Expresso Metropolitano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"caption\":\"Expresso Metropolitano\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/diego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/","og_locale":"es_MX","og_type":"article","og_title":"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES - Expresso Metropolitano","og_description":"La Diputaci\u00f3n Permanente, presidida por la diputada Martha Azucena Camacho Reynoso (morena), convoc\u00f3 a las, le y los diputados a la realizaci\u00f3n del Sexto Periodo Extraordinario de Sesiones de la LXII Legislatura mexiquense este 29 de mayo a las 10:00 horas para deliberar reformas referentes al Poder Judicial, nulidad de elecciones por intervenci\u00f3n extranjera y disposiciones del C\u00f3digo Electoral del Estado de M\u00e9xico.","og_url":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/","og_site_name":"Expresso Metropolitano","article_published_time":"2026-05-27T21:31:59+00:00","article_modified_time":"2026-05-29T21:42:25+00:00","og_image":[{"width":1600,"height":1067,"url":"http:\/\/expressometro.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg","type":"image\/jpeg"}],"author":"Expresso Metropolitano","twitter_misc":{"Escrito por":"Expresso Metropolitano","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/"},"author":{"name":"Expresso Metropolitano","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d"},"headline":"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES","datePublished":"2026-05-27T21:31:59+00:00","dateModified":"2026-05-29T21:42:25+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/"},"wordCount":703,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg","keywords":["Edomex","GEM"],"articleSection":["Gobierno","Otros","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/","url":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/","name":"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg","datePublished":"2026-05-27T21:31:59+00:00","dateModified":"2026-05-29T21:42:25+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2026\/05\/WhatsApp-Image-2026-05-27-at-9.46.18-PM.jpeg","width":1600,"height":1067},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2026\/05\/27\/convoca-diputacion-permanente-a-sexto-periodo-extraordinario-de-sesiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"CONVOCA DIPUTACI\u00d3N PERMANENTE A SEXTO PERIODO EXTRAORDINARIO DE SESIONES"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d","name":"Expresso Metropolitano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","caption":"Expresso Metropolitano"},"url":"https:\/\/expressometro.mx\/index.php\/author\/diego\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/11948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=11948"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/11948\/revisions"}],"predecessor-version":[{"id":11951,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/11948\/revisions\/11951"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/11950"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=11948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=11948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=11948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}