{"id":1055,"date":"2019-11-18T21:47:33","date_gmt":"2019-11-19T03:47:33","guid":{"rendered":"http:\/\/expressometro.mx\/?p=1055"},"modified":"2019-11-18T21:47:34","modified_gmt":"2019-11-19T03:47:34","slug":"asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/","title":{"rendered":"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Secretaria del Trabajo, Martha Hilda Gonz\u00e1lez Calder\u00f3n, encabez\u00f3 la instalaci\u00f3n del Comit\u00e9 de Gesti\u00f3n de Competencias, con lo que la dependencia a su cargo asume la facultad de capacitar, evaluar y certificar aptitudes laborales de las personas que desean acreditar de manera oficial sus conocimientos, habilidades, destrezas y actitudes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Luego de recibir el reconocimiento correspondiente, de manos del Director General del Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Laborales (Conocer), Rodrigo Alejandro Rojas Navarrete, la funcionaria&nbsp; dio a conocer que podr\u00e1n preparar a 120 conciliadores que formar\u00e1n parte del Centro Estatal de Conciliaci\u00f3n Laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Destac\u00f3 que en el Estado de M\u00e9xico, el Gobernador Alfredo Del Mazo Maza da muestras de trabajar de manera conjunta con el Gobierno de M\u00e9xico, particularmente una vez que fue aprobada en el Congreso local la Reforma Laboral, en la cual la conciliaci\u00f3n laboral constituye una prioridad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A partir de ahora, agreg\u00f3, se tendr\u00e1n est\u00e1ndares y herramientas para certificar habilidades laborales, instrumentos que no s\u00f3lo pueden aplicarse en el Estado de M\u00e9xico sino en otras entidades del pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por su parte, el Director General de Conocer, Rodrigo Alejandro Rojas Navarrete, se\u00f1al\u00f3 que el mundo laboral est\u00e1 en transformaci\u00f3n, marcado, entre otros aspectos, por la desaparici\u00f3n de las Juntas de Conciliaci\u00f3n y Arbitraje y la importancia adquirida por la mediaci\u00f3n laboral.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Indic\u00f3 que, desde Conocer, est\u00e1 convencido de la sinergia y la plena coordinaci\u00f3n del Gobierno federal con las entidades del pa\u00eds, para garantizar el \u00e9xito de los trabajos en la materia de certificaci\u00f3n de competencias laborales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ratific\u00f3 el compromiso de la instituci\u00f3n a su cargo con el sector productivo del Estado de M\u00e9xico y por seguir impulsando acciones que beneficien a las y los trabajadores de la entidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al encuentro asistieron los directores de la Secretar\u00eda del Trabajo, el Director de Promoci\u00f3n y Desarrollo de los Sectores Social y de Gobierno de Conocer, la Rectora de la Universidad Estatal del Valle de Toluca y el Director de la Facultad de Derecho de la Universidad Aut\u00f3noma del Estado de M\u00e9xico, entre otras autoridades.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretaria del Trabajo, Martha Hilda Gonz\u00e1lez Calder\u00f3n, encabez\u00f3 la instalaci\u00f3n del Comit\u00e9 de Gesti\u00f3n de Competencias, con lo que la dependencia a su cargo asume la facultad de capacitar, evaluar y certificar aptitudes laborales de las personas que desean acreditar de manera oficial sus conocimientos, habilidades, destrezas y actitudes. Luego de recibir el reconocimiento correspondiente, de manos del Director General del Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Laborales (Conocer), Rodrigo Alejandro Rojas Navarrete, la funcionaria&nbsp; dio a conocer que podr\u00e1n preparar a 120 conciliadores que formar\u00e1n parte&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1056,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-1055","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gobierno"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"La Secretaria del Trabajo, Martha Hilda Gonz\u00e1lez Calder\u00f3n, encabez\u00f3 la instalaci\u00f3n del Comit\u00e9 de Gesti\u00f3n de Competencias, con lo que la dependencia a su cargo asume la facultad de capacitar, evaluar y certificar aptitudes laborales de las personas que desean acreditar de manera oficial sus conocimientos, habilidades, destrezas y actitudes. Luego de recibir el reconocimiento correspondiente, de manos del Director General del Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Laborales (Conocer), Rodrigo Alejandro Rojas Navarrete, la funcionaria&nbsp; dio a conocer que podr\u00e1n preparar a 120 conciliadores que formar\u00e1n parte&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2019-11-19T03:47:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-11-19T03:47:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/11\/w2_10664_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"852\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expresso Metropolitano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expresso Metropolitano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/\"},\"author\":{\"name\":\"Expresso Metropolitano\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\"},\"headline\":\"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES\",\"datePublished\":\"2019-11-19T03:47:33+00:00\",\"dateModified\":\"2019-11-19T03:47:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/\"},\"wordCount\":380,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/w2_10664_1.jpg\",\"articleSection\":[\"Gobierno\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/\",\"name\":\"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/w2_10664_1.jpg\",\"datePublished\":\"2019-11-19T03:47:33+00:00\",\"dateModified\":\"2019-11-19T03:47:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/w2_10664_1.jpg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/11\\\/w2_10664_1.jpg\",\"width\":1280,\"height\":852},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2019\\\/11\\\/18\\\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\",\"name\":\"Expresso Metropolitano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"caption\":\"Expresso Metropolitano\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/diego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/","og_locale":"es_MX","og_type":"article","og_title":"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES - Expresso Metropolitano","og_description":"La Secretaria del Trabajo, Martha Hilda Gonz\u00e1lez Calder\u00f3n, encabez\u00f3 la instalaci\u00f3n del Comit\u00e9 de Gesti\u00f3n de Competencias, con lo que la dependencia a su cargo asume la facultad de capacitar, evaluar y certificar aptitudes laborales de las personas que desean acreditar de manera oficial sus conocimientos, habilidades, destrezas y actitudes. Luego de recibir el reconocimiento correspondiente, de manos del Director General del Consejo Nacional de Normalizaci\u00f3n y Certificaci\u00f3n de Competencias Laborales (Conocer), Rodrigo Alejandro Rojas Navarrete, la funcionaria&nbsp; dio a conocer que podr\u00e1n preparar a 120 conciliadores que formar\u00e1n parte&hellip;","og_url":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/","og_site_name":"Expresso Metropolitano","article_published_time":"2019-11-19T03:47:33+00:00","article_modified_time":"2019-11-19T03:47:34+00:00","og_image":[{"width":1280,"height":852,"url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/11\/w2_10664_1.jpg","type":"image\/jpeg"}],"author":"Expresso Metropolitano","twitter_misc":{"Escrito por":"Expresso Metropolitano","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/"},"author":{"name":"Expresso Metropolitano","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d"},"headline":"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES","datePublished":"2019-11-19T03:47:33+00:00","dateModified":"2019-11-19T03:47:34+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/"},"wordCount":380,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/11\/w2_10664_1.jpg","articleSection":["Gobierno"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/","url":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/","name":"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/11\/w2_10664_1.jpg","datePublished":"2019-11-19T03:47:33+00:00","dateModified":"2019-11-19T03:47:34+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/11\/w2_10664_1.jpg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/11\/w2_10664_1.jpg","width":1280,"height":852},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2019\/11\/18\/asume-secretaria-del-trabajo-estatal-facultad-para-certificar-competencias-laborales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"ASUME SECRETAR\u00cdA DEL TRABAJO ESTATAL FACULTAD PARA CERTIFICAR COMPETENCIAS LABORALES"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d","name":"Expresso Metropolitano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","caption":"Expresso Metropolitano"},"url":"https:\/\/expressometro.mx\/index.php\/author\/diego\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/1055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=1055"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/1055\/revisions"}],"predecessor-version":[{"id":1057,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/1055\/revisions\/1057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/1056"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=1055"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=1055"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=1055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}