{"id":10380,"date":"2024-10-30T14:58:54","date_gmt":"2024-10-30T20:58:54","guid":{"rendered":"https:\/\/expressometro.mx\/?p=10380"},"modified":"2024-11-05T15:01:21","modified_gmt":"2024-11-05T21:01:21","slug":"incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria","status":"publish","type":"post","link":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/","title":{"rendered":"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA"},"content":{"rendered":"\n<p>* El rector de la UAEM\u00e9x, Carlos Eduardo Barrera D\u00edaz, encabez\u00f3 la ceremonia de la 4\u00b0 Bienal Estudiantil de Ciencias y Tecnolog\u00eda 2024.<\/p>\n\n\n\n<p>* En esta edici\u00f3n se hizo entrega de reconocimientos a las y los representantes de seis proyectos ganadores.<\/p>\n\n\n\n<p>Con un total de 30 proyectos registrados -10 a nivel Licenciatura, 10 en Maestr\u00eda y 10 en Doctorado-, el rector de la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM\u00e9x), Carlos Eduardo Barrera D\u00edaz, encabez\u00f3 la ceremonia de la 4\u00b0 Bienal Estudiantil de Ciencias y Tecnolog\u00eda 2024, en el Patio del Centenario del Edificio de Rector\u00eda.<\/p>\n\n\n\n<p>Barrera D\u00edaz entreg\u00f3 reconocimientos a las y los representantes de los seis proyectos ganadores. A nivel Licenciatura, el primer lugar fue otorgado a Mar\u00eda Elizabeth S\u00e1nchez Guti\u00e9rrez y Ana Lilia L\u00f3pez Alc\u00e1ntara, y el segundo a Luis Eduardo Mart\u00ednez Salazar, Hugo Romero Garc\u00eda y Gabriela Joselin Pe\u00f1aloza Tapia. En la categor\u00eda de Maestr\u00eda, Karla Col\u00edn Garc\u00eda recibi\u00f3 el primer lugar, mientras que Cynthia Ang\u00e9lica Aguirre S\u00e1nchez obtuvo el segundo. Finalmente, en la categor\u00eda de Doctorado, el primer lugar fue para Ana Ver\u00f3nica Altamirano R\u00edos, y el segundo para Youssef Paolo Mendoza Zenil.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"840\" height=\"389\" src=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.48-PM-840x389.jpeg\" alt=\"\" class=\"wp-image-10383\" srcset=\"https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.48-PM-840x389.jpeg 840w, https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.48-PM-660x305.jpeg 660w, https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.48-PM-768x355.jpeg 768w, https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.48-PM.jpeg 1280w\" sizes=\"auto, (max-width: 840px) 100vw, 840px\" \/><\/figure>\n\n\n\n<p>La secretaria de Investigaci\u00f3n y Estudios Avanzados, Martha Patricia Zarza Delgado, asever\u00f3 que la Bienal Estudiantil de Ciencias y Tecnolog\u00eda tiene la finalidad de incentivar la calidad del estudiantado en el desarrollo cient\u00edfico del pa\u00eds.<\/p>\n\n\n\n<p>En este marco, coment\u00f3 que la UAEM\u00e9x tiene la funci\u00f3n sustantiva de crear conocimiento que impulse el desarrollo y bienestar de la sociedad, por ello, cuenta con 592 proyectos de investigaci\u00f3n registrados, la participaci\u00f3n de 712 docentes de tiempo completo en redes internacionales de investigaci\u00f3n, 890 acad\u00e9micas y acad\u00e9micos reconocidos en el Sistema Nacional de Investigadoras e Investigadores (SNII), as\u00ed como 111 programas de posgrado que atienden a 4 mil 228 estudiantes.<\/p>\n\n\n\n<p>Zarza Delgado resalt\u00f3 que, bajo una din\u00e1mica de trabajo colaborativo entre estudiantado y asesores, se genera una conciencia colectiva sobre el poder de la ciencia, pues funge como un medio que permite a las personas convivir en armon\u00eda con su entorno, por lo cual motiv\u00f3 a la comunidad universitaria a incentivar su curiosidad, a promover la innovaci\u00f3n y a seguir contribuyendo al progreso social, cultural y cient\u00edfico de M\u00e9xico.<\/p>\n\n\n\n<p>Por su parte, la investigadora de la Facultad de Ingenier\u00eda y asesora representante de la categor\u00eda \u201cLicenciatura\u201d, Rosa Mar\u00eda Valdovinos Rosas, puntualiz\u00f3 que este espacio dedicado a la ciencia y la tecnolog\u00eda refleja el compromiso de la Aut\u00f3noma mexiquense con la vanguardia acad\u00e9mica y de investigaci\u00f3n, contribuyendo a la formaci\u00f3n de las y los futuros profesionales preparados para enfrentar y resolver estrat\u00e9gicamente desaf\u00edos globales como el cambio clim\u00e1tico, salud p\u00fablica y sostenibilidad.<\/p>\n\n\n\n<p>Al acto asistieron integrantes del Gabinete Universitario y del Colegio de Directores; asesores y asesoras de los proyectos finalistas; invitados e invitadas de la Secretar\u00eda de Investigaci\u00f3n y Estudios Avanzados, as\u00ed como la comunidad universitaria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un total de 30 proyectos registrados -10 a nivel Licenciatura, 10 en Maestr\u00eda y 10 en Doctorado-, el rector de la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM\u00e9x), Carlos Eduardo Barrera D\u00edaz, encabez\u00f3 la ceremonia de la 4\u00b0 Bienal Estudiantil de Ciencias y Tecnolog\u00eda 2024, en el Patio del Centenario del Edificio de Rector\u00eda.<\/p>\n","protected":false},"author":1,"featured_media":10382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[108,3,1,231],"tags":[313,1982,86,82],"class_list":["post-10380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-educacion","category-gobierno","category-otros","category-politica","tag-carlos-eduardo-barrera-diaz","tag-edomex","tag-gem","tag-uaemex"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA - Expresso Metropolitano<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA - Expresso Metropolitano\" \/>\n<meta property=\"og:description\" content=\"Con un total de 30 proyectos registrados -10 a nivel Licenciatura, 10 en Maestr\u00eda y 10 en Doctorado-, el rector de la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM\u00e9x), Carlos Eduardo Barrera D\u00edaz, encabez\u00f3 la ceremonia de la 4\u00b0 Bienal Estudiantil de Ciencias y Tecnolog\u00eda 2024, en el Patio del Centenario del Edificio de Rector\u00eda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Expresso Metropolitano\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-30T20:58:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-05T21:01:21+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Expresso Metropolitano\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Expresso Metropolitano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/\"},\"author\":{\"name\":\"Expresso Metropolitano\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\"},\"headline\":\"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA\",\"datePublished\":\"2024-10-30T20:58:54+00:00\",\"dateModified\":\"2024-11-05T21:01:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/\"},\"wordCount\":529,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg\",\"keywords\":[\"Carlos Eduardo Barrera D\u00edaz\",\"Edomex\",\"GEM\",\"UAEMex\"],\"articleSection\":[\"Educaci\u00f3n\",\"Gobierno\",\"Otros\",\"Pol\u00edtica\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/\",\"name\":\"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA - Expresso Metropolitano\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg\",\"datePublished\":\"2024-10-30T20:58:54+00:00\",\"dateModified\":\"2024-11-05T21:01:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg\",\"width\":800,\"height\":533},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/2024\\\/10\\\/30\\\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/expressometro.mx\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#website\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"name\":\"Expresso Metropolitano\",\"description\":\"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis\",\"publisher\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/expressometro.mx\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#organization\",\"name\":\"Expresso Metropolitano\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/expressometro.mx\\\/wp-content\\\/uploads\\\/2019\\\/07\\\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg\",\"width\":290,\"height\":73,\"caption\":\"Expresso Metropolitano\"},\"image\":{\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/expressometro.mx\\\/#\\\/schema\\\/person\\\/efa971b4a0664db8ed5c22b1b0dd2f5d\",\"name\":\"Expresso Metropolitano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g\",\"caption\":\"Expresso Metropolitano\"},\"url\":\"https:\\\/\\\/expressometro.mx\\\/index.php\\\/author\\\/diego\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA - Expresso Metropolitano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/","og_locale":"es_MX","og_type":"article","og_title":"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA - Expresso Metropolitano","og_description":"Con un total de 30 proyectos registrados -10 a nivel Licenciatura, 10 en Maestr\u00eda y 10 en Doctorado-, el rector de la Universidad Aut\u00f3noma del Estado de M\u00e9xico (UAEM\u00e9x), Carlos Eduardo Barrera D\u00edaz, encabez\u00f3 la ceremonia de la 4\u00b0 Bienal Estudiantil de Ciencias y Tecnolog\u00eda 2024, en el Patio del Centenario del Edificio de Rector\u00eda.","og_url":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/","og_site_name":"Expresso Metropolitano","article_published_time":"2024-10-30T20:58:54+00:00","article_modified_time":"2024-11-05T21:01:21+00:00","og_image":[{"width":800,"height":533,"url":"http:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg","type":"image\/jpeg"}],"author":"Expresso Metropolitano","twitter_misc":{"Escrito por":"Expresso Metropolitano","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#article","isPartOf":{"@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/"},"author":{"name":"Expresso Metropolitano","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d"},"headline":"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA","datePublished":"2024-10-30T20:58:54+00:00","dateModified":"2024-11-05T21:01:21+00:00","mainEntityOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/"},"wordCount":529,"commentCount":0,"publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg","keywords":["Carlos Eduardo Barrera D\u00edaz","Edomex","GEM","UAEMex"],"articleSection":["Educaci\u00f3n","Gobierno","Otros","Pol\u00edtica"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/","url":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/","name":"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA - Expresso Metropolitano","isPartOf":{"@id":"https:\/\/expressometro.mx\/#website"},"primaryImageOfPage":{"@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#primaryimage"},"image":{"@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#primaryimage"},"thumbnailUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg","datePublished":"2024-10-30T20:58:54+00:00","dateModified":"2024-11-05T21:01:21+00:00","breadcrumb":{"@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#primaryimage","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-05-at-2.59.37-PM.jpeg","width":800,"height":533},{"@type":"BreadcrumbList","@id":"https:\/\/expressometro.mx\/index.php\/2024\/10\/30\/incentiva-uaemex-el-desarrollo-cientifico-y-tecnologico-de-su-comunidad-universitaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/expressometro.mx\/"},{"@type":"ListItem","position":2,"name":"INCENTIVA UAEM\u00c9X EL DESARROLLO CIENT\u00cdFICO Y TECNOL\u00d3GICO DE SU COMUNIDAD UNIVERSITARIA"}]},{"@type":"WebSite","@id":"https:\/\/expressometro.mx\/#website","url":"https:\/\/expressometro.mx\/","name":"Expresso Metropolitano","description":"Periodismo comprometido, informaci\u00f3n, investigaci\u00f3n y an\u00e1lisis","publisher":{"@id":"https:\/\/expressometro.mx\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/expressometro.mx\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/expressometro.mx\/#organization","name":"Expresso Metropolitano","url":"https:\/\/expressometro.mx\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/","url":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","contentUrl":"https:\/\/expressometro.mx\/wp-content\/uploads\/2019\/07\/cropped-Logo-Expresso-Metropolitano-1-1.jpeg","width":290,"height":73,"caption":"Expresso Metropolitano"},"image":{"@id":"https:\/\/expressometro.mx\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/expressometro.mx\/#\/schema\/person\/efa971b4a0664db8ed5c22b1b0dd2f5d","name":"Expresso Metropolitano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a89f802b8de18c6952f223c88d3d106e9e3679839f4e25a02f4a6cc2ae6ba3b3?s=96&d=mm&r=g","caption":"Expresso Metropolitano"},"url":"https:\/\/expressometro.mx\/index.php\/author\/diego\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/10380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/comments?post=10380"}],"version-history":[{"count":1,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/10380\/revisions"}],"predecessor-version":[{"id":10384,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/posts\/10380\/revisions\/10384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media\/10382"}],"wp:attachment":[{"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/media?parent=10380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/categories?post=10380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/expressometro.mx\/index.php\/wp-json\/wp\/v2\/tags?post=10380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}